{"id":4474,"date":"2020-10-19T15:37:05","date_gmt":"2020-10-19T13:37:05","guid":{"rendered":"https:\/\/auto-bezpieczniki.pl\/?p=4474"},"modified":"2020-10-19T15:37:05","modified_gmt":"2020-10-19T13:37:05","slug":"ford-mustang-2005-2009-skrzynka-bezpiecznikow","status":"publish","type":"post","link":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/2020\/10\/19\/ford-mustang-2005-2009-skrzynka-bezpiecznikow\/","title":{"rendered":"Ford Mustang (2005-2009) \u2013 skrzynka bezpiecznik\u00f3w"},"content":{"rendered":"<h2><span>Ford Mustang (2005-2009) &#8211; schemat skrzynki bezpiecznik\u00f3w<\/span><\/h2>\n<p><span><strong>Rok produkcji:<\/strong> 2005, 2006, 2007, 2008, 2009.<\/span><\/p>\n<p><strong>Bezpiecznik zapalniczki (gniazdo zasilania) w Fordzie Transit (2014-2018)<\/strong> to bezpiecznik F13 w skrzynce bezpiecznikowej<\/p>\n<h3><span>Panel bezpiecznik\u00f3w przedzia\u0142u pasa\u017cerskiego<\/span><\/h3>\n<figure id=\"attachment_18724\" class=\"wp-caption alignnone\" aria-describedby=\"caption-attachment-18724\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4475\" src=\"https:\/\/auto-bezpieczniki.pl\/wp-content\/uploads\/2020\/10\/Ford-Mustang-2005-2009-\u2013-skrzynka-bezpiecznikow.jpg\" alt=\"\" width=\"300\" height=\"120\" \/><figcaption id=\"caption-attachment-18724\" class=\"wp-caption-text\"><span>Ford Mustang &#8211; schemat skrzynki bezpiecznik\u00f3w &#8211; przedzia\u0142 pasa\u017cerski<\/span><\/figcaption><\/figure>\n<table class=\"table table-hover table-bordered\">\n<tbody>\n<tr>\n<td><span>Bezpiecznik<\/span><\/td>\n<td><span>Ampery [A]<\/span><\/td>\n<td><span>Opis<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>3<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>Moc wycieraczek \/ przeka\u017anik silnika dmuchawy<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>4<\/span><\/td>\n<td><span>5<\/span><\/td>\n<td><span>Lusterka elektryczne<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>5<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>6<\/span><\/td>\n<td><span>5<\/span><\/td>\n<td><span>Dodatkowe \u017ar\u00f3d\u0142a op\u00f3\u017anienia<\/span><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\"><span>7<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><b><span>2005:<\/span><\/b><span> \u00a0Overdrive anulunie<\/span><br \/>\n<b><span>2006, zamienny:<\/span><\/b><span> \u00a0Overdrive anulowanie<\/span><br \/>\n<b><span>2007-2009:<\/span><\/b><span>\u00a0\u00a0Elektrochromowe lustro<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>5<\/span><\/td>\n<td><b><span>2006, coupe:<\/span><\/b><span>\u00a0\u00a0anulowanie Overdrive<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>8<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>Klaster, z\u0142\u0105cze \u0142\u0105cza danych (DLC)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>9<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>10<\/span><\/td>\n<td><span>5<\/span><\/td>\n<td><span>Modu\u0142 wykrywania w\u0142ama\u0144 (15 M), kontrola klimatu<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>11<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>12<\/span><\/td>\n<td><span>5<\/span><\/td>\n<td><span>Kontrola klimatu.\u00a0Zap\u0142on<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>13<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>14<\/span><\/td>\n<td><span>5<\/span><\/td>\n<td><span>Prze\u0142\u0105cznik cyklu klimatyzacji<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>15<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>W\u0142\u0105czanie \/ wy\u0142\u0105czanie hamulca (BOO)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>16<\/span><\/td>\n<td><span>5<\/span><\/td>\n<td><span>Grupa<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>17<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>Modu\u0142 kontroli bezpiecze\u0144stwa (RCM), system wykrywania pasa\u017cer\u00f3w (PODS), wska\u017anik dezaktywacji poduszki powietrznej pasa\u017cera (PADI)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>18<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>Uk\u0142ad przeciwblokuj\u0105cy (ABS), podgrzewacz zaworu wentylacji dodatniej skrzyni korbowej (PCV) (2005-2006), zap\u0142on (2005-2006)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>19<\/span><\/td>\n<td><span>5<\/span><\/td>\n<td><span>Przeka\u017aniki modu\u0142u sterowania zespo\u0142em nap\u0119dowym (PCM), pasywny system antykradzie\u017cowy (PATS), lampka ostrzegawcza poduszki powietrznej zestawu wska\u017anik\u00f3w (2007-2009)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>20<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>Radio (start)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>21<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>Przeka\u017anik rozrusznika<\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\"><b><span>Przeka\u017anik<\/span><\/b><\/td>\n<\/tr>\n<tr>\n<td><span>1<\/span><\/td>\n<td colspan=\"2\"><span>Op\u00f3\u017anienie akcesori\u00f3w # 1<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>2<\/span><\/td>\n<td colspan=\"2\"><span>&#8211;<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h3 align=\"left\"><span>Skrzynka rozdzielcza zasilania<\/span><\/h3>\n<figure id=\"attachment_18725\" class=\"wp-caption alignnone\" aria-describedby=\"caption-attachment-18725\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4476\" src=\"https:\/\/auto-bezpieczniki.pl\/wp-content\/uploads\/2020\/10\/Ford-Mustang-2005-2009-\u2013-skrzynka-bezpiecznikow-2.jpg\" alt=\"\" width=\"300\" height=\"155\" \/><figcaption id=\"caption-attachment-18725\" class=\"wp-caption-text\"><span>Ford Mustang &#8211; schemat skrzynki bezpiecznik\u00f3w &#8211; rozdzia\u0142 mocy<\/span><\/figcaption><\/figure>\n<table class=\"table table-hover table-bordered\">\n<tbody>\n<tr>\n<td><span>Numer<\/span><\/td>\n<td><span>Ampery [A]<\/span><\/td>\n<td><span>Opis<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>1<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>2<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>Dmuchawa klimatyzacyjna<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>3<\/span><\/td>\n<td><span>40<\/span><\/td>\n<td><span>Wentylator ch\u0142odz\u0105cy<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>4<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>Rozrusznik<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>5<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><b><span>2005:<\/span><\/b><span>\u00a0\u00a0Silnik prawej przedniej szyby<\/span><br \/>\n<b><span>2006-2009:<\/span><\/b><span>\u00a0Silnik\u00a0\u00a0lewej przedniej szyby<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>6<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>Wzmacniacz tylny (radio Shaker 1000)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>7<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><b><span>2005:<\/span><\/b><span>\u00a0\u00a0Silnik lewej przedniej szyby<\/span><br \/>\n<b><span>2006-2009:<\/span><\/b><span>\u00a0Silnik\u00a0\u00a0prawej przedniej szyby<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>8<\/span><\/td>\n<td><span>40<\/span><\/td>\n<td><span>Uk\u0142ad przeciwblokuj\u0105cy (ABS) # 1<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>9<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>Wzmacniacz tylny (radio Shaker 1000)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>10<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>Wycieraczki<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>11<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>Silnik lewej tylnej szyby (tylko kabriolet)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>12<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>Silnik prawej szyby tylnej (tylko kabriolet)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>13<\/span><\/td>\n<td><span>40<\/span><\/td>\n<td><span>Rozk\u0142adany top<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>14<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><b><span>2005-2006:<\/span><\/b><span>\u00a0\u00a0Siedzenie<\/span><br \/>\n<b><span>2007-2009:<\/span><\/b><span>\u00a0\u00a0Siedzenie kierowcy<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>15<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><b><span>2007-2009:<\/span><\/b><span>\u00a0\u00a0Fotel pasa\u017cera<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>16<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>Wzmacniacz przedni (radio Shaker 500)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>39<\/span><\/td>\n<td><span>15<\/span><\/td>\n<td><b><span>2007-2009:<\/span><\/b><span>\u00a0\u00a0Silnik nr 4<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>40<\/span><\/td>\n<td><span>15<\/span><\/td>\n<td><span>Silnik nr 2<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>41<\/span><\/td>\n<td><span>15<\/span><\/td>\n<td><span>Pompa paliwowa<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>42<\/span><\/td>\n<td><span>15<\/span><\/td>\n<td><span>Silnik nr 3<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>43<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>Alternator<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>44<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>Op\u00f3\u017anione akcesorium<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>45<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>PCM<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>46<\/span><\/td>\n<td><span>25<\/span><\/td>\n<td><span>Klakson<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>47<\/span><\/td>\n<td><span>15<\/span><\/td>\n<td><span>Silnik nr 1<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>49<\/span><\/td>\n<td><span>15<\/span><\/td>\n<td><span>Sprz\u0119g\u0142o klimatyzacji<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>50<\/span><\/td>\n<td><span>15<\/span><\/td>\n<td><span>Wysokie belki<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>51<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><span>Rozk\u0142adany top<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>52<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>Odmra\u017cacz tylny<\/span><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\"><span>54<\/span><\/td>\n<td><span>10<\/span><\/td>\n<td><b><span>2005-2006:<\/span><\/b><span>\u00a0\u00a0op\u00f3\u017anienie PCM<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>20<\/span><\/td>\n<td><b><span>2008-2009:<\/span><\/b><span>\u00a0\u00a0Lewy reflektor HID<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>55<\/span><\/td>\n<td><span>20<\/span><\/td>\n<td><b><span>2008-2009:<\/span><\/b><span>\u00a0\u00a0prawy reflektor HID<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>56<\/span><\/td>\n<td><span>20<\/span><\/td>\n<td><span>Radio, SDARS (2007-2009)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>57<\/span><\/td>\n<td><span>20<\/span><\/td>\n<td>&#8211;<\/td>\n<\/tr>\n<tr>\n<td><span>58<\/span><\/td>\n<td><span>15<\/span><\/td>\n<td><span>\u015awiat\u0142a przeciwmgielne<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>59<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>SJB # 5 (skrzynka bezpiecznik\u00f3w tablicy rozdzielczej)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>60<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>61<\/span><\/td>\n<td><span>20<\/span><\/td>\n<td><span>Punkt zasilania # 1 (tablica przyrz\u0105d\u00f3w)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>62<\/span><\/td>\n<td><span>20<\/span><\/td>\n<td><span>SJB # 7 (skrzynka bezpiecznik\u00f3w tablicy rozdzielczej)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>63<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>SJB # 6 (skrzynka bezpiecznik\u00f3w tablicy przyrz\u0105d\u00f3w)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>64<\/span><\/td>\n<td><span>20<\/span><\/td>\n<td><span>Punkt zasilania # 2 (konsola)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>65<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>ABS # 2<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>66<\/span><\/td>\n<td><span>25<\/span><\/td>\n<td><b><span>2007-2009:<\/span><\/b><span>\u00a0\u00a0Podgrzewane siedzenia<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>67<\/span><\/td>\n<td><span>30<\/span><\/td>\n<td><span>SJB # 4 (skrzynka bezpiecznik\u00f3w tablicy rozdzielczej)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>68<\/span><\/td>\n<td><span>20<\/span><\/td>\n<td><span>Zap\u0142on<\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\"><b><span>Przeka\u017anik<\/span><\/b><\/td>\n<\/tr>\n<tr>\n<td><span>20<\/span><\/td>\n<td colspan=\"2\"><span>PCM # 2<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>21<\/span><\/td>\n<td colspan=\"2\"><span>Pompa paliwowa<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>22<\/span><\/td>\n<td colspan=\"2\"><span>Rozrusznik<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>23<\/span><\/td>\n<td colspan=\"2\"><b><span>2005-2006:<\/span><\/b><span>\u00a0\u00a0PCM nr 1<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>24<\/span><\/td>\n<td colspan=\"2\"><span>Sprz\u0119g\u0142o klimatyzacji<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>25<\/span><\/td>\n<td colspan=\"2\"><span>Wentylator ch\u0142odz\u0105cy (wysoka pr\u0119dko\u015b\u0107)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>26<\/span><\/td>\n<td colspan=\"2\"><span>Klakson<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>27<\/span><\/td>\n<td colspan=\"2\"><span>Wysokie belki<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>28<\/span><\/td>\n<td colspan=\"2\"><span>Wentylator ch\u0142odz\u0105cy (niska pr\u0119dko\u015b\u0107)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>29<\/span><\/td>\n<td colspan=\"2\"><span>Odmra\u017cacz tylny<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>30<\/span><\/td>\n<td colspan=\"2\"><span>\u015awiat\u0142a przeciwmgielne<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>31<\/span><\/td>\n<td colspan=\"2\"><span>Rozk\u0142adany dach (g\u00f3ra)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>32<\/span><\/td>\n<td colspan=\"2\"><span>Dmuchawa klimatyzacyjna<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>33<\/span><\/td>\n<td colspan=\"2\"><span>Rozk\u0142adany dach (d\u00f3\u0142)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>34<\/span><\/td>\n<td colspan=\"2\"><b><span>2006-2009:<\/span><\/b><span>\u00a0 Klapa baga\u017cnika<\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\"><b><span>Dioda<\/span><\/b><b><br \/>\n<\/b><\/td>\n<\/tr>\n<tr>\n<td><span>48<\/span><\/td>\n<td colspan=\"2\"><b><span>2005-2008:<\/span><\/b><span>\u00a0\u00a0Sprz\u0119g\u0142o klimatyzacji<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>53<\/span><\/td>\n<td colspan=\"2\"><span>PCM<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><span>Przeka\u017anik pomocniczy z reflektorami HID (2008-2009)<\/span><\/h3>\n<p><span>W pojazdach wyposa\u017conych w reflektory HID skrzynka przeka\u017anik\u00f3w pomocniczych znajduje si\u0119 pod mask\u0105 po prawej stronie z przodu komory silnika.\u00a0Ta skrzynka przeka\u017anik\u00f3w pomocniczych zawiera przeka\u017aniki lewego przedniego i prawego przedniego reflektora HID.<\/span><\/p>\n<figure id=\"attachment_18726\" class=\"wp-caption alignnone\" aria-describedby=\"caption-attachment-18726\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4477\" src=\"https:\/\/auto-bezpieczniki.pl\/wp-content\/uploads\/2020\/10\/Ford-Mustang-2005-2009-\u2013-skrzynka-bezpiecznikow-3.jpg\" alt=\"\" width=\"241\" height=\"134\" \/><figcaption id=\"caption-attachment-18726\" class=\"wp-caption-text\"><span>Ford Mustang &#8211; schemat skrzynki bezpiecznik\u00f3w &#8211; skrzynka przeka\u017anik\u00f3w pomocniczych<\/span><\/figcaption><\/figure>\n<table class=\"table table-hover table-bordered\">\n<tbody>\n<tr>\n<td><span>Numer<\/span><\/td>\n<td><span>Opis<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>1<\/span><\/td>\n<td><span>Lewy reflektor HID<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>2<\/span><\/td>\n<td><span>Prawe \u015bwiat\u0142o g\u0142\u00f3wne HID<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>3<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td><span>4<\/span><\/td>\n<td><span>&#8211;<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Ford Mustang (2005-2009) &#8211; schemat skrzynki bezpiecznik\u00f3w Rok produkcji: 2005, 2006, 2007, 2008, 2009. Bezpiecznik zapalniczki (gniazdo zasilania) w Fordzie<\/p>\n","protected":false},"author":1,"featured_media":4478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,84],"tags":[874,897],"class_list":["post-4474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ford","category-mustang","tag-ford","tag-ford-mustang"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/wp\/v2\/posts\/4474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/wp\/v2\/comments?post=4474"}],"version-history":[{"count":0,"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/wp\/v2\/posts\/4474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/wp\/v2\/media?parent=4474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/wp\/v2\/categories?post=4474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/auto-bezpieczniki.com.pl\/index.php\/wp-json\/wp\/v2\/tags?post=4474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}